{"id":17215,"date":"2020-02-12T14:00:21","date_gmt":"2020-02-12T13:00:21","guid":{"rendered":"https:\/\/www.althallercommunication.de\/?p=17215"},"modified":"2023-12-14T11:58:07","modified_gmt":"2023-12-14T10:58:07","slug":"muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus","status":"publish","type":"post","link":"https:\/\/althallercommunication.de\/en\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/","title":{"rendered":"M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus"},"content":{"rendered":"<p><\/p>\n<p><strong>Zahlungsdienstleister Ratepay neu auf Kundenliste des Softwarespezialisten hawk:AI.<br \/>\n<\/strong><\/p>\n<h3><strong>M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus<br \/>\n<\/strong><\/h3>\n<p><strong>M\u00fcnchen, den 12. Februar 2020 &#8211; hawk:AI baut die Kundenbasis f\u00fcr seine Cloud-basierte L\u00f6sung zur Erkennung und Bearbeitung von Geldw\u00e4scheverdachtsf\u00e4llen kontinuierlich aus. Mit Ratepay hat der M\u00fcnchener Softwarespezialist einen der wachstumsst\u00e4rksten Zahlungsdienstleister als Neukunden hinzugewonnen. hawk:AI unterst\u00fctzt und optimiert dabei die f\u00fcr Zahlungsdienstleister vorgeschriebenen Prozesse nach dem \u201eGesetz \u00fcber das Aufsp\u00fcren von Gewinnen aus schweren Straftaten \u2013 Geldw\u00e4schegesetz (GwG)\u201c, das auch f\u00fcr andere Institute wie Banken und Versicherer gilt.<\/strong><\/p>\n<p>\u201eWir haben uns f\u00fcr die L\u00f6sung von hawk:AI entschieden, da uns eine flexible, erweiterbare L\u00f6sung, die sich reibungslos in unsere IT-Landschaft integrieren l\u00e4sst, besonders wichtig war\u201c, begr\u00fcndet Charlotte Ruffin, Compliance Officer von Ratepay, die Entscheidung f\u00fcr hawk:AI und erl\u00e4utert: \u201eDas Team von hawk:AI war in der Lage, unsere Anforderungen in wenigen Wochen umzusetzen und den Betrieb zu etablieren. Das hat uns geholfen, unsere internen Abl\u00e4ufe regulierungskonform zu optimieren und deutlich effizienter zu gestalten.\u201c<\/p>\n<p>Geldw\u00e4sche ist ein brisantes Thema: Jedes Jahr werden zwischen zwei und f\u00fcnf Prozent des weltweiten Bruttosozialprodukts gewaschen. In Deutschland sind es laut einer Studie des Finanzministeriums rund 100 Milliarden Euro.<\/p>\n<p>Tobias Schweiger, CEO von hawk:AI erl\u00e4utert: \u201eIn der Zusammenarbeit mit Ratepay konnten wir zeigen, dass unsere modulare L\u00f6sung f\u00fcr einen schnell wachsenden Zahlungsdienstleister mit speziellen Anforderungen aus dem Online-Payment Bereich sehr schnell einsetzbar ist. Die Auslieferung der L\u00f6sung als Software-as-a-Service (SaaS) sowie unsere standardisierten und flexiblen IT-Schnittstellen haben dies unterst\u00fctzt. In Zusammenarbeit mit Ratepay konnten wir die Anpassung von Workflows, Systemintelligenz und Dokumentation zur Umsetzung der Compliance-Anforderungen schnell umsetzen.\u201c<\/p>\n<p>Mit dem Kundengewinn von Ratepay schreibt hawk:AI seine Erfolgsgeschichte kontinuierlich weiter. Erst k\u00fcrzlich konnte das M\u00fcnchener Fintech die Wirtschaftspr\u00fcfungs- und Beratungsgesellschaft PwC als strategischen Partner gewinnen. F\u00fcr die Unternehmensentwicklung des in 2018 gegr\u00fcndeten Startups hawk:AI ist mit der Zusammenarbeit mit Ratepay ein wichtiges Signal gesetzt.<\/p>\n<p><strong>\u00dcber Ratepay<\/strong><br \/>\nRatepay ist der f\u00fchrende Anbieter f\u00fcr Payment-L\u00f6sungen mit hundertprozentiger Zahlungsgarantie in Europa. Zu den Produkten z\u00e4hlen Rechnungskauf, Ratenzahlung mit sofortiger Onlinezusage, Lastschrift und Vorkasse. Die Ratepay GmbH mit Sitz in Berlin wurde im Dezember 2009 gegr\u00fcndet, besch\u00e4ftigt mehr als 250 Mitarbeiter und geh\u00f6rt zur Nets Group.<\/p>\n<p>Weitere Informationen erhalten Sie unter <a href=\"http:\/\/www.ratepay.com\">www.ratepay.com<\/a><\/p>\n<p><strong>\u00dcber hawk:AI<\/strong><br \/>\nAls f\u00fchrende Softwarefirma unterst\u00fctzt hawk:AI ihre Kunden weltweit mit hocheffizienten und innovativen, zukunftsweisenden L\u00f6sungen mit dem Ziel der verbesserten Erkennung und Bearbeitung von Verdachtsf\u00e4llen der Geldw\u00e4sche oder der Terrorismusfinanzierung (AML\/CFT).<\/p>\n<p>Kreditinstitute und andere Finanzinstitute nutzen hawk:AI zur Optimierung von regulatorisch vorgeschriebenen AML\/CFT Prozessen. hawk:AI Produktmodule umfassen die Optimierung von Regeln, Erkennung u. Bearbeitung von Verdachtsf\u00e4llen, Filterung von Fehlalarmen sowie die Transparenzmachung von Kriminalit\u00e4tsmustern und stellen dabei ein Komplettangebot f\u00fcr den Bereich AML-Compliance dar. hawk:AI steht dabei f\u00fcr deutlich erh\u00f6hte Prozesseffizienz, aber auch f\u00fcr ein reduziertes Compliance-Risiko im Vergleich zu herk\u00f6mmlich eingesetzten L\u00f6sungen. Dies wird durch hochmoderne Softwarearchitektur und den innovativen Einsatz von K\u00fcnstlicher Intelligenz m\u00f6glich und ist jederzeit nachvollziehbar.<\/p>\n<p>hawk:AI wurde 2018 von erfahrenen Spezialisten im Bereich Finanztechnologie gegr\u00fcndet und hat seinen Sitz in M\u00fcnchen.<br \/>\nWeitere Informationen erhalten Sie unter <a href=\"http:\/\/www.hawk.ai\">www.hawk.ai<\/a><\/p>\n<p><a href=\"https:\/\/althallercommunication.de\/wp-content\/uploads\/2020\/02\/hawkAI_Ratepay_03022020.pdf\">PI zum Download<\/a><\/p>\n<p><\/p>\n<p>Bildmaterial<\/p>\n<p>https:\/\/althallercommunication.de\/wp-content\/uploads\/2020\/02\/hawkAI_Tobias_Schweiger.jpgTobias Schweiger, CEO von hawk:AI erl\u00e4utert: \u201eIn der Zusammenarbeit mit Ratepay konnten wir zeigen, dass unsere modulare L\u00f6sung f\u00fcr einen schnell wachsenden Zahlungsdienstleister mit speziellen Anforderungen aus dem Online-Payment Bereich sehr schnell einsetzbar ist. Die Auslieferung der L\u00f6sung als Software-as-a-Service (SaaS) sowie unsere standardisierten und flexiblen IT-Schnittstellen haben dies unterst\u00fctzt. In Zusammenarbeit mit Ratepay konnten wir die Anpassung von Workflows, Systemintelligenz und Dokumentation zur Umsetzung der Compliance-Anforderungen schnell umsetzen.\u201chttps:\/\/althallercommunication.de\/wp-content\/uploads\/2020\/02\/Ratepay_Charlotte_Ruffin.jpg\u201eWir haben uns f\u00fcr die L\u00f6sung von hawk:AI entschieden, da uns eine flexible, erweiterbare L\u00f6sung, die sich reibungslos in unsere IT-Landschaft integrieren l\u00e4sst, besonders wichtig war\u201c, begr\u00fcndet Charlotte Ruffin, Compliance Officer von Ratepay, die Entscheidung f\u00fcr hawk:AI und erl\u00e4utert: \u201eDas Team von hawk:AI war in der Lage, unsere Anforderungen in wenigen Wochen umzusetzen und den Betrieb zu etablieren. Das hat uns geholfen, unsere internen Abl\u00e4ufe regulierungskonform zu optimieren und deutlich effizienter zu gestalten.\u201cMehr News von hawk:AIW2Z1c2lvbl9idXR0b24gbGluaz0mcXVvdDtqYXZhc2NyaXB0Omhpc3RvcnkuYmFjaygpJnF1b3Q7IHRpdGxlPSZxdW90OyZxdW90OyB0YXJnZXQ9JnF1b3Q7X3NlbGYmcXVvdDsgYWxpZ25tZW50PSZxdW90O2NlbnRlciZxdW90OyBtb2RhbD0mcXVvdDsmcXVvdDsgaGlkZV9vbl9tb2JpbGU9JnF1b3Q7c21hbGwtdmlzaWJpbGl0eSxtZWRpdW0tdmlzaWJpbGl0eSxsYXJnZS12aXNpYmlsaXR5JnF1b3Q7IGNsYXNzPSZxdW90OyZxdW90OyBpZD0mcXVvdDsmcXVvdDsgY29sb3I9JnF1b3Q7ZGVmYXVsdCZxdW90OyBidXR0b25fZ3JhZGllbnRfdG9wX2NvbG9yPSZxdW90OyZxdW90OyBidXR0b25fZ3JhZGllbnRfYm90dG9tX2NvbG9yPSZxdW90OyZxdW90OyBidXR0b25fZ3JhZGllbnRfdG9wX2NvbG9yX2hvdmVyPSZxdW90OyZxdW90OyBidXR0b25fZ3JhZGllbnRfYm90dG9tX2NvbG9yX2hvdmVyPSZxdW90OyZxdW90OyBhY2NlbnRfY29sb3I9JnF1b3Q7JnF1b3Q7IGFjY2VudF9ob3Zlcl9jb2xvcj0mcXVvdDsmcXVvdDsgdHlwZT0mcXVvdDsmcXVvdDsgYmV2ZWxfY29sb3I9JnF1b3Q7JnF1b3Q7IGJvcmRlcl93aWR0aD0mcXVvdDsmcXVvdDsgc2l6ZT0mcXVvdDttZWRpdW0mcXVvdDsgc3RyZXRjaD0mcXVvdDtkZWZhdWx0JnF1b3Q7IHNoYXBlPSZxdW90O3JvdW5kJnF1b3Q7IGljb249JnF1b3Q7ZmEtY2hldnJvbi1sZWZ0JnF1b3Q7IGljb25fcG9zaXRpb249JnF1b3Q7bGVmdCZxdW90OyBpY29uX2RpdmlkZXI9JnF1b3Q7bm8mcXVvdDsgYW5pbWF0aW9uX3R5cGU9JnF1b3Q7JnF1b3Q7IGFuaW1hdGlvbl9kaXJlY3Rpb249JnF1b3Q7bGVmdCZxdW90OyBhbmltYXRpb25fc3BlZWQ9JnF1b3Q7MC4zJnF1b3Q7IGFuaW1hdGlvbl9vZmZzZXQ9JnF1b3Q7JnF1b3Q7XXp1csO8Y2tbL2Z1c2lvbl9idXR0b25d<\/p>\n<p>Pressekontakt und Redaktion<br \/>\n<strong>Jacqueline Althaller<br \/>\n<\/strong>ALTHALLER communication GbR<br \/>\nElisabethstra\u00dfe 13<br \/>\n80796 M\u00fcnchen<\/p>\n<p><em>Bildmaterial stellen wir auf Wunsch gerne zur Verf\u00fcgung.<\/em><\/p>\n<p><\/p>\n<p>+49 (0) 89 38 66 52 61<\/p>\n<p><\/p>\n<p>+49 (0) 89 38 66 52 75<\/p>\n<p><\/p>\n<p><a href=\"mailto:info@althallercommunication.de\">info@althallercommunication.de<\/a><\/p>\n<p><\/p>\n<p><a href=\"https:\/\/althallercommunication.de\/\">www.althallercommunication.de<\/a><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>hawk:AI<\/strong> | M\u00fcnchen: <\/br> hawk:AI baut die Kundenbasis f\u00fcr seine Cloud-basierte L\u00f6sung zur Erkennung und Bearbeitung von Geldw\u00e4scheverdachtsf\u00e4llen kontinuierlich aus.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[2765,2756,1,2751,2758],"tags":[1491,1392,1493,1489,1492,1389,1419,2820,1488,1490,1390],"class_list":["post-17215","post","type-post","status-publish","format-standard","hentry","category-klassische-pressearbeit","category-kunden-in-den-medien","category-unkategorisiert","category-payment-finance","category-pressemeldungen","tag-charlotte-ruffin","tag-geldwaesche","tag-geldwaeschegesetz","tag-geldwaeschpraevention","tag-gwg","tag-hawkai","tag-kuenstliche-intelligenz","tag-payment-en","tag-ratepay","tag-startup","tag-tobias-schweiger"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus<\/title>\n<meta name=\"description\" content=\"hawk:AI baut die Kundenbasis f\u00fcr seine Cloud-basierte L\u00f6sung zur Erkennung und Bearbeitung von Geldw\u00e4scheverdachtsf\u00e4llen kontinuierlich aus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus\" \/>\n<meta property=\"og:description\" content=\"hawk:AI baut die Kundenbasis f\u00fcr seine Cloud-basierte L\u00f6sung zur Erkennung und Bearbeitung von Geldw\u00e4scheverdachtsf\u00e4llen kontinuierlich aus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/\" \/>\n<meta property=\"og:site_name\" content=\"althaller communication\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/althallercommunication\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-12T13:00:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-14T10:58:07+00:00\" \/>\n<meta name=\"author\" content=\"Jacqueline Althaller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ALTHALLERcom\" \/>\n<meta name=\"twitter:site\" content=\"@ALTHALLERcom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jacqueline Althaller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\\\/\"},\"author\":{\"name\":\"Jacqueline Althaller\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#\\\/schema\\\/person\\\/4ca72b5e8d0bebc1f9b3061e463e32ee\"},\"headline\":\"M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus\",\"datePublished\":\"2020-02-12T13:00:21+00:00\",\"dateModified\":\"2023-12-14T10:58:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\\\/\"},\"wordCount\":1612,\"publisher\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#organization\"},\"keywords\":[\"Charlotte Ruffin\",\"Geldw\u00e4sche\",\"Geldw\u00e4schegesetz\",\"Geldw\u00e4schpr\u00e4vention\",\"GWG\",\"hawk:AI\",\"K\u00fcnstliche Intelligenz\",\"Payment\",\"Ratepay\",\"Startup\",\"Tobias Schweiger\"],\"articleSection\":[\"Klassische Pressearbeit\",\"Kunden\",\"Others\",\"Payment &amp; Finance\",\"Pressemeldungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\\\/\",\"url\":\"https:\\\/\\\/althallercommunication.de\\\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\\\/\",\"name\":\"M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#website\"},\"datePublished\":\"2020-02-12T13:00:21+00:00\",\"dateModified\":\"2023-12-14T10:58:07+00:00\",\"description\":\"hawk:AI baut die Kundenbasis f\u00fcr seine Cloud-basierte L\u00f6sung zur Erkennung und Bearbeitung von Geldw\u00e4scheverdachtsf\u00e4llen kontinuierlich aus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/althallercommunication.de\\\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/althallercommunication.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#website\",\"url\":\"https:\\\/\\\/althallercommunication.de\\\/\",\"name\":\"althaller communication\",\"description\":\"Martkommunikation B2B\",\"publisher\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/althallercommunication.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#organization\",\"name\":\"ALTHALLER communication\",\"url\":\"https:\\\/\\\/althallercommunication.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/althallercommunication.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/althaller_comm_b.png\",\"contentUrl\":\"https:\\\/\\\/althallercommunication.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/althaller_comm_b.png\",\"width\":464,\"height\":110,\"caption\":\"ALTHALLER communication\"},\"image\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/althallercommunication\",\"https:\\\/\\\/x.com\\\/ALTHALLERcom\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3332596?trk=tyah&amp;amp;amp;trkInfo=tas:COMMUNICATION Presse und PR,idx:1-1-1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#\\\/schema\\\/person\\\/4ca72b5e8d0bebc1f9b3061e463e32ee\",\"name\":\"Jacqueline Althaller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g\",\"caption\":\"Jacqueline Althaller\"},\"description\":\"$$$2021hmb8hzb4MD\",\"url\":\"https:\\\/\\\/althallercommunication.de\\\/en\\\/author\\\/jacqueline-althaller\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus","description":"hawk:AI baut die Kundenbasis f\u00fcr seine Cloud-basierte L\u00f6sung zur Erkennung und Bearbeitung von Geldw\u00e4scheverdachtsf\u00e4llen kontinuierlich aus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/","og_locale":"en_US","og_type":"article","og_title":"M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus","og_description":"hawk:AI baut die Kundenbasis f\u00fcr seine Cloud-basierte L\u00f6sung zur Erkennung und Bearbeitung von Geldw\u00e4scheverdachtsf\u00e4llen kontinuierlich aus.","og_url":"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/","og_site_name":"althaller communication","article_publisher":"https:\/\/www.facebook.com\/althallercommunication","article_published_time":"2020-02-12T13:00:21+00:00","article_modified_time":"2023-12-14T10:58:07+00:00","author":"Jacqueline Althaller","twitter_card":"summary_large_image","twitter_creator":"@ALTHALLERcom","twitter_site":"@ALTHALLERcom","twitter_misc":{"Written by":"Jacqueline Althaller","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/#article","isPartOf":{"@id":"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/"},"author":{"name":"Jacqueline Althaller","@id":"https:\/\/althallercommunication.de\/#\/schema\/person\/4ca72b5e8d0bebc1f9b3061e463e32ee"},"headline":"M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus","datePublished":"2020-02-12T13:00:21+00:00","dateModified":"2023-12-14T10:58:07+00:00","mainEntityOfPage":{"@id":"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/"},"wordCount":1612,"publisher":{"@id":"https:\/\/althallercommunication.de\/#organization"},"keywords":["Charlotte Ruffin","Geldw\u00e4sche","Geldw\u00e4schegesetz","Geldw\u00e4schpr\u00e4vention","GWG","hawk:AI","K\u00fcnstliche Intelligenz","Payment","Ratepay","Startup","Tobias Schweiger"],"articleSection":["Klassische Pressearbeit","Kunden","Others","Payment &amp; Finance","Pressemeldungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/","url":"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/","name":"M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus","isPartOf":{"@id":"https:\/\/althallercommunication.de\/#website"},"datePublished":"2020-02-12T13:00:21+00:00","dateModified":"2023-12-14T10:58:07+00:00","description":"hawk:AI baut die Kundenbasis f\u00fcr seine Cloud-basierte L\u00f6sung zur Erkennung und Bearbeitung von Geldw\u00e4scheverdachtsf\u00e4llen kontinuierlich aus.","breadcrumb":{"@id":"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/althallercommunication.de\/muenchener-startup-hawkai-baut-geschaeft-kontinuierlich-aus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/althallercommunication.de\/en\/"},{"@type":"ListItem","position":2,"name":"M\u00fcnchener Startup hawk:AI baut Gesch\u00e4ft kontinuierlich aus"}]},{"@type":"WebSite","@id":"https:\/\/althallercommunication.de\/#website","url":"https:\/\/althallercommunication.de\/","name":"althaller communication","description":"Martkommunikation B2B","publisher":{"@id":"https:\/\/althallercommunication.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/althallercommunication.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/althallercommunication.de\/#organization","name":"ALTHALLER communication","url":"https:\/\/althallercommunication.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/althallercommunication.de\/#\/schema\/logo\/image\/","url":"https:\/\/althallercommunication.de\/wp-content\/uploads\/2023\/12\/althaller_comm_b.png","contentUrl":"https:\/\/althallercommunication.de\/wp-content\/uploads\/2023\/12\/althaller_comm_b.png","width":464,"height":110,"caption":"ALTHALLER communication"},"image":{"@id":"https:\/\/althallercommunication.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/althallercommunication","https:\/\/x.com\/ALTHALLERcom","https:\/\/www.linkedin.com\/company\/3332596?trk=tyah&amp;amp;amp;trkInfo=tas:COMMUNICATION Presse und PR,idx:1-1-1"]},{"@type":"Person","@id":"https:\/\/althallercommunication.de\/#\/schema\/person\/4ca72b5e8d0bebc1f9b3061e463e32ee","name":"Jacqueline Althaller","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g","caption":"Jacqueline Althaller"},"description":"$$$2021hmb8hzb4MD","url":"https:\/\/althallercommunication.de\/en\/author\/jacqueline-althaller\/"}]}},"_links":{"self":[{"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/posts\/17215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/comments?post=17215"}],"version-history":[{"count":5,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/posts\/17215\/revisions"}],"predecessor-version":[{"id":17230,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/posts\/17215\/revisions\/17230"}],"wp:attachment":[{"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/media?parent=17215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/categories?post=17215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/tags?post=17215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}