{"id":30365,"date":"2024-05-28T09:02:17","date_gmt":"2024-05-28T07:02:17","guid":{"rendered":"https:\/\/althallercommunication.de\/?p=30365"},"modified":"2024-08-09T14:41:07","modified_gmt":"2024-08-09T12:41:07","slug":"beim-e-payment-droht-ein-neues-gefaehrdungsszenario","status":"publish","type":"post","link":"https:\/\/althallercommunication.de\/en\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/","title":{"rendered":"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario"},"content":{"rendered":"<p>Ob simpler Betrug oder Hackerangriffe \u2013 gegen die g\u00e4ngigen Methoden Cyberkrimineller sind die E-Payment-Dienstleister heute gut gewappnet. Doch Computop-Chef Ralf Gladis warnt: Mit der zunehmenden Verf\u00fcgbarkeit von Quantencomputern entsteht ein neue Gef\u00e4hrdung.<br \/>\nWie steht es um die Sicherheit im E-Payment? Ralf Gladis, Mitgr\u00fcnder und Gesch\u00e4ftsf\u00fchrer des Payment Service Providers Computop, zeichnet im Gespr\u00e4ch mit ChannelPartner ein eher positives Bild der aktuellen Situation. Geht es um die Gef\u00e4hrdung durch Hackerangriffe Cyberkrimineller, so sind dagegen heute durchgehend effektive Schutzmechanismen im Einsatz. &#8220;F\u00fcr Payment Service Provider gilt der sogenannten PCI-Datensicherheitsstandard, der zum Schutz von Kreditkartendaten entwickelt wurde. Die Sicherheit wird dabei durch die Verschl\u00fcsselung von Kreditkartendaten erreicht. Dies erm\u00f6glicht eine schnelle und nahtlose Abwicklung von E-Commerce- und Card-not-Present-Transaktionen mit einem hohen Ma\u00df an Vertrauen zwischen H\u00e4ndlern, Kunden, Banken und Zahlungsdienstleistern&#8221;, erkl\u00e4rt der E-Payment-Experte. Au\u00dferdem stelle sein Unternehmen sicher, dass eine durchgehende IT-Verf\u00fcgbarkeit, der Einsatz schutzstarker Firewalls und die Umsetzung organisatorischer Sicherheit gem\u00e4\u00df ISO-Richtlinien eine effektive Absicherung gew\u00e4hrleisteten.<\/p>\n<p>Aus diesem Grund haben sich Cyberkriminelle in den letzten Jahren haupts\u00e4chlich auf sogenannten Fraud bzw. Betrugsmethoden verlagert. Ein h\u00e4ufiges Beispiel stellt der Identit\u00e4tsdiebstahl dar, bei dem Kriminelle an die Daten von Online-Kunden geraten und diese f\u00fcr ihre verbrecherischen Zwecke einsetzen. Doch auch hier existieren mittlerweile effektive Schutzmechanismen. Dazu geh\u00f6ren die inzwischen fl\u00e4chendeckend angebotene Zwei-Faktor-Authentisierung, aber auch verhaltensorientierte Betrugsabwehrma\u00dfnahmen wie die sogenannten Velocity Checks, die zum Beispiel untypisch h\u00e4ufige Bestellungen identifizieren sollen. Auch wenn diese Abwehrma\u00dfnahmen von den Anbietern gerne mit dem Etikett &#8220;KI&#8221; beworben werden, handelt es sich dabei in der Regel vor allem um Machine Learning Anwendungen. Doch hat deren Weiterentwicklung dazu beigetragen, dass Schutz-Level gegen Online Fraud immer h\u00f6her zu legen&#8230;<\/p>\n<p>Zum vollst\u00e4ndigen Artikel gelangen Sie <a href=\"https:\/\/www.channelpartner.de\/a\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario,3618110\">hier<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ob simpler Betrug oder Hackerangriffe \u2013 gegen die g\u00e4ngigen Methoden Cyberkrimineller sind die E-Payment-Dienstleister heute gut gewappnet. Doch Computop-Chef Ralf Gladis warnt: Mit der zunehmenden Verf\u00fcgbarkeit von Quantencomputern entsteht ein neue Gef\u00e4hrdung.<br \/>\nWie steht es um die Sicherheit im E-Payment? Ralf Gladis, Mitgr\u00fcnder und Gesch\u00e4ftsf\u00fchrer des Payment Service Providers Computop, zeichnet im Gespr\u00e4ch mit ChannelPartner ein eher positives Bild der aktuellen Situation. Geht es um die Gef\u00e4hrdung durch Hackerangriffe Cyberkrimineller, so sind dagegen heute durchgehend effektive Schutzmechanismen im Einsatz. &#8220;F\u00fcr Payment Service Provider gilt der sogenannten PCI-Datensicherheitsstandard, der zum Schutz von Kreditkartendaten entwickelt wurde. Die Sicherheit wird dabei durch die Verschl\u00fcsselung von Kreditkartendaten erreicht. Dies erm\u00f6glicht eine schnelle und nahtlose Abwicklung von E-Commerce- und Card-not-Present-Transaktionen mit einem hohen Ma\u00df an Vertrauen zwischen H\u00e4ndlern, Kunden, Banken und Zahlungsdienstleistern&#8221;, erkl\u00e4rt der E-Payment-Experte. Au\u00dferdem stelle sein Unternehmen sicher, dass eine durchgehende IT-Verf\u00fcgbarkeit, der Einsatz schutzstarker Firewalls und die Umsetzung organisatorischer Sicherheit gem\u00e4\u00df ISO-Richtlinien eine effektive Absicherung gew\u00e4hrleisteten.<\/p>\n<p>Aus diesem Grund haben sich Cyberkriminelle in den letzten Jahren haupts\u00e4chlich auf sogenannten Fraud bzw. Betrugsmethoden verlagert. Ein h\u00e4ufiges Beispiel stellt der Identit\u00e4tsdiebstahl dar, bei dem Kriminelle an die Daten von Online-Kunden geraten und diese f\u00fcr ihre verbrecherischen Zwecke einsetzen. Doch auch hier existieren mittlerweile effektive Schutzmechanismen. Dazu geh\u00f6ren die inzwischen fl\u00e4chendeckend angebotene Zwei-Faktor-Authentisierung, aber auch verhaltensorientierte Betrugsabwehrma\u00dfnahmen wie die sogenannten Velocity Checks, die zum Beispiel untypisch h\u00e4ufige Bestellungen identifizieren sollen. Auch wenn diese Abwehrma\u00dfnahmen von den Anbietern gerne mit dem Etikett &#8220;KI&#8221; beworben werden, handelt es sich dabei in der Regel vor allem um Machine Learning Anwendungen. Doch hat deren Weiterentwicklung dazu beigetragen, dass Schutz-Level gegen Online Fraud immer h\u00f6her zu legen&#8230;<\/p>\n<p>Zum vollst\u00e4ndigen Artikel gelangen Sie hier<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[2757,2841,2751],"tags":[],"class_list":["post-30365","post","type-post","status-publish","format-standard","hentry","category-clippings","category-computop","category-payment-finance"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario | althaller communication<\/title>\n<meta name=\"description\" content=\"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario. Ob simpler Betrug oder Hackerangriffe \u2013 gegen die g\u00e4ngigen Methoden Cyberkrimineller sind die E-Payment-Dienstleister heute gut gewappnet\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario\" \/>\n<meta property=\"og:description\" content=\"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario. Ob simpler Betrug oder Hackerangriffe \u2013 gegen die g\u00e4ngigen Methoden Cyberkrimineller sind die E-Payment-Dienstleister heute gut gewappnet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/\" \/>\n<meta property=\"og:site_name\" content=\"althaller communication\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/althallercommunication\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-28T07:02:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-09T12:41:07+00:00\" \/>\n<meta name=\"author\" content=\"Jacqueline Althaller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ALTHALLERcom\" \/>\n<meta name=\"twitter:site\" content=\"@ALTHALLERcom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jacqueline Althaller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\\\/\"},\"author\":{\"name\":\"Jacqueline Althaller\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#\\\/schema\\\/person\\\/4ca72b5e8d0bebc1f9b3061e463e32ee\"},\"headline\":\"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario\",\"datePublished\":\"2024-05-28T07:02:17+00:00\",\"dateModified\":\"2024-08-09T12:41:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\\\/\"},\"wordCount\":306,\"publisher\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#organization\"},\"articleSection\":[\"Clippings\",\"Computop\",\"Payment &amp; Finance\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\\\/\",\"url\":\"https:\\\/\\\/althallercommunication.de\\\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\\\/\",\"name\":\"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario | althaller communication\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#website\"},\"datePublished\":\"2024-05-28T07:02:17+00:00\",\"dateModified\":\"2024-08-09T12:41:07+00:00\",\"description\":\"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario. Ob simpler Betrug oder Hackerangriffe \u2013 gegen die g\u00e4ngigen Methoden Cyberkrimineller sind die E-Payment-Dienstleister heute gut gewappnet\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/althallercommunication.de\\\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/althallercommunication.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#website\",\"url\":\"https:\\\/\\\/althallercommunication.de\\\/\",\"name\":\"althaller communication\",\"description\":\"Martkommunikation B2B\",\"publisher\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/althallercommunication.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#organization\",\"name\":\"ALTHALLER communication\",\"url\":\"https:\\\/\\\/althallercommunication.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/althallercommunication.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/althaller_comm_b.png\",\"contentUrl\":\"https:\\\/\\\/althallercommunication.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/althaller_comm_b.png\",\"width\":464,\"height\":110,\"caption\":\"ALTHALLER communication\"},\"image\":{\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/althallercommunication\",\"https:\\\/\\\/x.com\\\/ALTHALLERcom\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3332596?trk=tyah&amp;amp;amp;trkInfo=tas:COMMUNICATION Presse und PR,idx:1-1-1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/althallercommunication.de\\\/#\\\/schema\\\/person\\\/4ca72b5e8d0bebc1f9b3061e463e32ee\",\"name\":\"Jacqueline Althaller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g\",\"caption\":\"Jacqueline Althaller\"},\"description\":\"$$$2021hmb8hzb4MD\",\"url\":\"https:\\\/\\\/althallercommunication.de\\\/en\\\/author\\\/jacqueline-althaller\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario | althaller communication","description":"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario. Ob simpler Betrug oder Hackerangriffe \u2013 gegen die g\u00e4ngigen Methoden Cyberkrimineller sind die E-Payment-Dienstleister heute gut gewappnet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/","og_locale":"en_US","og_type":"article","og_title":"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario","og_description":"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario. Ob simpler Betrug oder Hackerangriffe \u2013 gegen die g\u00e4ngigen Methoden Cyberkrimineller sind die E-Payment-Dienstleister heute gut gewappnet","og_url":"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/","og_site_name":"althaller communication","article_publisher":"https:\/\/www.facebook.com\/althallercommunication","article_published_time":"2024-05-28T07:02:17+00:00","article_modified_time":"2024-08-09T12:41:07+00:00","author":"Jacqueline Althaller","twitter_card":"summary_large_image","twitter_creator":"@ALTHALLERcom","twitter_site":"@ALTHALLERcom","twitter_misc":{"Written by":"Jacqueline Althaller","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/#article","isPartOf":{"@id":"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/"},"author":{"name":"Jacqueline Althaller","@id":"https:\/\/althallercommunication.de\/#\/schema\/person\/4ca72b5e8d0bebc1f9b3061e463e32ee"},"headline":"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario","datePublished":"2024-05-28T07:02:17+00:00","dateModified":"2024-08-09T12:41:07+00:00","mainEntityOfPage":{"@id":"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/"},"wordCount":306,"publisher":{"@id":"https:\/\/althallercommunication.de\/#organization"},"articleSection":["Clippings","Computop","Payment &amp; Finance"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/","url":"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/","name":"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario | althaller communication","isPartOf":{"@id":"https:\/\/althallercommunication.de\/#website"},"datePublished":"2024-05-28T07:02:17+00:00","dateModified":"2024-08-09T12:41:07+00:00","description":"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario. Ob simpler Betrug oder Hackerangriffe \u2013 gegen die g\u00e4ngigen Methoden Cyberkrimineller sind die E-Payment-Dienstleister heute gut gewappnet","breadcrumb":{"@id":"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/althallercommunication.de\/beim-e-payment-droht-ein-neues-gefaehrdungsszenario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/althallercommunication.de\/en\/"},{"@type":"ListItem","position":2,"name":"Beim E-Payment droht ein neues Gef\u00e4hrdungsszenario"}]},{"@type":"WebSite","@id":"https:\/\/althallercommunication.de\/#website","url":"https:\/\/althallercommunication.de\/","name":"althaller communication","description":"Martkommunikation B2B","publisher":{"@id":"https:\/\/althallercommunication.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/althallercommunication.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/althallercommunication.de\/#organization","name":"ALTHALLER communication","url":"https:\/\/althallercommunication.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/althallercommunication.de\/#\/schema\/logo\/image\/","url":"https:\/\/althallercommunication.de\/wp-content\/uploads\/2023\/12\/althaller_comm_b.png","contentUrl":"https:\/\/althallercommunication.de\/wp-content\/uploads\/2023\/12\/althaller_comm_b.png","width":464,"height":110,"caption":"ALTHALLER communication"},"image":{"@id":"https:\/\/althallercommunication.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/althallercommunication","https:\/\/x.com\/ALTHALLERcom","https:\/\/www.linkedin.com\/company\/3332596?trk=tyah&amp;amp;amp;trkInfo=tas:COMMUNICATION Presse und PR,idx:1-1-1"]},{"@type":"Person","@id":"https:\/\/althallercommunication.de\/#\/schema\/person\/4ca72b5e8d0bebc1f9b3061e463e32ee","name":"Jacqueline Althaller","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e8cdf7784b763130efe210406ba46634d04913cf12c46cf98b2799d6da47211?s=96&d=mm&r=g","caption":"Jacqueline Althaller"},"description":"$$$2021hmb8hzb4MD","url":"https:\/\/althallercommunication.de\/en\/author\/jacqueline-althaller\/"}]}},"_links":{"self":[{"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/posts\/30365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/comments?post=30365"}],"version-history":[{"count":1,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/posts\/30365\/revisions"}],"predecessor-version":[{"id":30366,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/posts\/30365\/revisions\/30366"}],"wp:attachment":[{"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/media?parent=30365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/categories?post=30365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/althallercommunication.de\/en\/wp-json\/wp\/v2\/tags?post=30365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}